{"id":1174,"date":"2020-03-03T15:18:01","date_gmt":"2020-03-03T15:18:01","guid":{"rendered":"http:\/\/amandioanastacio.de\/?p=1174"},"modified":"2020-07-01T15:50:34","modified_gmt":"2020-07-01T15:50:34","slug":"opera-dos-3-vintens","status":"publish","type":"post","link":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/","title":{"rendered":"\u00d3PERA DOS 3 VINT\u00c9NS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1174\" class=\"elementor elementor-1174\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dc2b1b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2dc2b1b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48946ebd\" data-id=\"48946ebd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23d2bc1f elementor-widget elementor-widget-heading\" data-id=\"23d2bc1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">\u00d3PERA DOS 3 VINT\u00c9NS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-004ed03 elementor-widget elementor-widget-heading\" data-id=\"004ed03\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Die Dreigroschenoper<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a176193 elementor-widget elementor-widget-text-editor\" data-id=\"a176193\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bertolt Brecht und Kurt Weill<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a92880b elementor-widget__width-auto elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"4a92880b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vimeo.com\/187278386\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROMO ANZEIGEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f1752e2 elementor-widget__width-auto elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"4f1752e2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:geral@almadarame.pt\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BUCHEN SIE DIESE SHOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e704f2f\" data-id=\"5e704f2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bcdead2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bcdead2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-155f1af0\" data-id=\"155f1af0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78a038ad elementor-widget elementor-widget-heading\" data-id=\"78a038ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">MEINE ROLLE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f0cc0de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f0cc0de\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-47a79f94\" data-id=\"47a79f94\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cce6419 elementor-widget elementor-widget-image\" data-id=\"6cce6419\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"423\" height=\"279\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera1.jpg\" class=\"attachment-full size-full wp-image-1155\" alt=\"\" srcset=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera1.jpg 423w, https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera1-300x198.jpg 300w\" sizes=\"(max-width: 423px) 100vw, 423px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-383f5d71 elementor-widget elementor-widget-heading\" data-id=\"383f5d71\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">KREATION<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f05380 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"54f05380\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-31fc6608\" data-id=\"31fc6608\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39b814ba elementor-widget elementor-widget-image\" data-id=\"39b814ba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"420\" height=\"277\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera3.jpg\" class=\"attachment-full size-full wp-image-1159\" alt=\"\" srcset=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera3.jpg 420w, https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera3-300x198.jpg 300w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66aa083a elementor-widget elementor-widget-heading\" data-id=\"66aa083a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">K\u00dcNSTLERISCHE LEITUNG<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592c0c9e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"592c0c9e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-321a737f\" data-id=\"321a737f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ba08bb elementor-widget elementor-widget-image\" data-id=\"78ba08bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"422\" height=\"280\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera4.jpg\" class=\"attachment-full size-full wp-image-1161\" alt=\"\" srcset=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera4.jpg 422w, https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera4-300x199.jpg 300w\" sizes=\"(max-width: 422px) 100vw, 422px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eecafaf elementor-widget elementor-widget-heading\" data-id=\"6eecafaf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">SZENOGRAPHIE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b07fdf4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5b07fdf4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cf746fe elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"4cf746fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-586df2e6\" data-id=\"586df2e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30821aea elementor-widget elementor-widget-text-editor\" data-id=\"30821aea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcBER<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5746fe63 elementor-widget elementor-widget-heading\" data-id=\"5746fe63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00d3PERA DOS 3 VINT\u00c9NS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-389419d0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"389419d0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-45c161\" data-id=\"45c161\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c66e elementor-widget elementor-widget-text-editor\" data-id=\"78c66e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir haben uns der Herausforderung dieses St\u00fcckes im Rahmen eines Berufspraktikums der Sch\u00fcler der Jazz-Schule Of\u00edcio das Artes gestellt. So schlugen wir vor, Die Dreigroschenoper mit dramaturgischer und musikalischer Unterst\u00fctzung aufzuf\u00fchren, mit der Absicht, eine gemeinsame Sprache zwischen Jazz, Narrativ und der komplexen Musik von Kurt Weill herzustellen und jungen Studenten den ersten Kontakt mit einem Referenzwerk im Bereich Musik und Theater zu erm\u00f6glichen. Indem wir der Kreativit\u00e4t dieser jungen Leute freien Lauf lassen wollten, inszenierten wir den ersten Akt dieses komplexen und zeitlosen Werkes basierend auf einer zeitgen\u00f6ssischen \u00c4sthetik nahe an sozialen Brennpunktvierteln im Umland von Gro\u00dfst\u00e4dten.<\/p><p>Das St\u00fcck setzt sich aus vier Rollengruppen zusammen: Banditen, Bettlern, Polizisten und Prostituierten. Mackie Messer ist der Chef der Banditen, und Herr Peachum ist der Eigent\u00fcmer der Firma, die die Bettler kontrolliert und ausbeutet. Die Aufdeckung des dramatischen Konflikts ist nur vor\u00fcbergehend und heuristisch, sie ist jedoch ein notwendiger erster Schritt.<br \/>Der Konflikt beginnt, als Mackie Messer und Polly Peachum (die Tochter von Peachum) beschlie\u00dfen, zu heiraten, was dadurch gestoppt wird, dass Peachum Druck auf Londons Polizeichef, Tiger Brown, Mackie Messers langj\u00e4hrigen Freund, aus\u00fcbt.<\/p><p>Die Dreigroschenoper [&#8230;] ist ein Referat \u00fcber das, was der Zuschauer im Theater vom Leben zu sehen w\u00fcnscht. Da er jedoch gleichzeitig auch einiges sieht, was er nicht zu sehen w\u00fcnscht, da er also seine W\u00fcnsche nicht nur ausgef\u00fchrt, sondern auch kritisiert sieht, [\u2026], <br \/>ist er prinzipiell imstande, dem Theater eine neue Funktion zu erteilen. <br \/>(Brecht 1967: 67)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6410a422\" data-id=\"6410a422\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ac2c8e9 elementor-widget elementor-widget-image\" data-id=\"7ac2c8e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"422\" height=\"280\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\" class=\"attachment-full size-full wp-image-1157\" alt=\"\" srcset=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg 422w, https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1-300x199.jpg 300w\" sizes=\"(max-width: 422px) 100vw, 422px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78b5a08e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78b5a08e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-684f505\" data-id=\"684f505\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-862cd30 elementor-widget elementor-widget-heading\" data-id=\"862cd30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">K\u00dcNSTLERISCHES DATENBLATT <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20dcdc0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20dcdc0e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2682e927\" data-id=\"2682e927\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10bc1bc0 elementor-widget elementor-widget-text-editor\" data-id=\"10bc1bc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>K\u00fcnstlerische Leitung, Adaption und Szenografie <\/b> | Am\u00e2ndio Anast\u00e1cio<\/p><p><b>Musikalische Leitung<\/b> | Jo\u00e3o Bastos<\/p><p><b>Interpretation<\/b> | Ana Casa Branca, Marcela Nascimento, Soraia Caldeira, Patr\u00edcia Valente, Diana Lingui\u00e7a, Sandra Borges, Susana Figueiredo, Sofia Viola and Jo\u00e3o Carvalho.<\/p><p><b>Musiker<\/b> | Abdulay Correia, Ant\u00f3nio Arimatea, Artur Ferreira, Daniel Moura, Eliana Louren\u00e7o Gilea Neves, Gilner Batista, Gon\u00e7alo Almod\u00f4var, Gon\u00e7alo Gomes, Jo\u00e3o Viola, Josias D\u2019Assun\u00e7\u00e3o, Lamine Carvalho, Lu\u00eds Fradinho, Manuel Candeias, Pedro Silva, Pedro Aldeias and R\u00faben Domingues.<\/p><p><b>Produktion<\/b> | Alexandra Anast\u00e1cio and Carla Pomares<\/p><p><b>Kost\u00fcme<\/b> | Ana Vilhena<\/p><p><b>Make-up<\/b> | Ana Vilhena, Ana Candeias, In\u00eas Samina<\/p><p><b>Lichtdesign<\/b> | Am\u00e2ndio Anast\u00e1cio and Jo\u00e3o Sofio<\/p><p><b>Tontechniker<\/b> | Paulo Alface<\/p><p><b>Fotografie und Video<\/b> | In\u00eas Samina<\/p><p><b>Grafik-Design<\/b> | Jo\u00e3o Baltazar Martins<\/p><p><b>DAUER<\/b><br \/>70 min.<\/p><p><b>FREIGEGEBEN AB\u00a0<\/b><br \/>12+<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c2cc5fa\" data-id=\"5c2cc5fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c6ab22c elementor-widget elementor-widget-video\" data-id=\"6c6ab22c\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/187278386?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7146835a elementor-widget elementor-widget-text-editor\" data-id=\"7146835a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-size: 15px;\"><b>Co-Production<\/b> | Alma d&#8217;Arame and Of\u00edcio das Artes<\/p><p style=\"font-size: 15px;\"><b>Supported\u00a0by<\/b>\u00a0| Montemor-o-Novo City Council<\/p><p style=\"font-size: 15px;\"><b>Partners<\/b> | Of\u00edcio das Artes<\/p><p style=\"font-size: 15px;\"><b>Organisation funded by<\/b>\u00a0| DGARTES and the Portuguese Government<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d1e36f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d1e36f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1846ef6e\" data-id=\"1846ef6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ca61606 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5ca61606\" data-element_type=\"widget\" data-settings=\"{&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5ca61606\" data-elementor-lightbox-title=\"opera4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE2MSwidXJsIjoiaHR0cHM6XC9cL2FtYW5kaW9hbmFzdGFjaW8uZGVcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzAxXC9vcGVyYTQuanBnIiwic2xpZGVzaG93IjoiNWNhNjE2MDYifQ%3D%3D\" href=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera4.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera4-150x150.jpg\" alt=\"opera4\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5ca61606\" data-elementor-lightbox-title=\"opera3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE1OSwidXJsIjoiaHR0cHM6XC9cL2FtYW5kaW9hbmFzdGFjaW8uZGVcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzAxXC9vcGVyYTMuanBnIiwic2xpZGVzaG93IjoiNWNhNjE2MDYifQ%3D%3D\" href=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera3.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera3-150x150.jpg\" alt=\"opera3\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5ca61606\" data-elementor-lightbox-title=\"opera2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE1NywidXJsIjoiaHR0cHM6XC9cL2FtYW5kaW9hbmFzdGFjaW8uZGVcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzAxXC9vcGVyYTItMS5qcGciLCJzbGlkZXNob3ciOiI1Y2E2MTYwNiJ9\" href=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1-150x150.jpg\" alt=\"opera2\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5ca61606\" data-elementor-lightbox-title=\"opera1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE1NSwidXJsIjoiaHR0cHM6XC9cL2FtYW5kaW9hbmFzdGFjaW8uZGVcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMTlcLzAxXC9vcGVyYTEuanBnIiwic2xpZGVzaG93IjoiNWNhNjE2MDYifQ%3D%3D\" href=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera1-150x150.jpg\" alt=\"opera1\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00d3PERA DOS 3 VINT\u00c9NS Die Dreigroschenoper Bertolt Brecht und Kurt Weill PROMO ANZEIGEN BUCHEN SIE DIESE SHOW MEINE ROLLE KREATION K\u00dcNSTLERISCHE LEITUNG SZENOGRAPHIE \u00dcBER \u00d3PERA DOS 3 VINT\u00c9NS Wir haben uns der Herausforderung dieses St\u00fcckes im Rahmen eines Berufspraktikums der Sch\u00fcler der Jazz-Schule Of\u00edcio das Artes gestellt. So schlugen wir vor, Die Dreigroschenoper mit dramaturgischer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1158,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00d3PERA DOS 3 VINT\u00c9NS - Am\u00e2ndio Anast\u00e1cio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d3PERA DOS 3 VINT\u00c9NS - Am\u00e2ndio Anast\u00e1cio\" \/>\n<meta property=\"og:description\" content=\"\u00d3PERA DOS 3 VINT\u00c9NS Die Dreigroschenoper Bertolt Brecht und Kurt Weill PROMO ANZEIGEN BUCHEN SIE DIESE SHOW MEINE ROLLE KREATION K\u00dcNSTLERISCHE LEITUNG SZENOGRAPHIE \u00dcBER \u00d3PERA DOS 3 VINT\u00c9NS Wir haben uns der Herausforderung dieses St\u00fcckes im Rahmen eines Berufspraktikums der Sch\u00fcler der Jazz-Schule Of\u00edcio das Artes gestellt. So schlugen wir vor, Die Dreigroschenoper mit dramaturgischer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\" \/>\n<meta property=\"og:site_name\" content=\"Am\u00e2ndio Anast\u00e1cio\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-03T15:18:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-01T15:50:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"422\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"http:\/\/amandioanastacio.de\/#\/schema\/person\/4fbfed1ca752c302a8bc5a034d59adb6\"},\"headline\":\"\u00d3PERA DOS 3 VINT\u00c9NS\",\"datePublished\":\"2020-03-03T15:18:01+00:00\",\"dateModified\":\"2020-07-01T15:50:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/amandioanastacio.de\/#organization\"},\"image\":{\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\",\"url\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\",\"name\":\"\u00d3PERA DOS 3 VINT\u00c9NS - Am\u00e2ndio Anast\u00e1cio\",\"isPartOf\":{\"@id\":\"http:\/\/amandioanastacio.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\",\"datePublished\":\"2020-03-03T15:18:01+00:00\",\"dateModified\":\"2020-07-01T15:50:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage\",\"url\":\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\",\"contentUrl\":\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg\",\"width\":422,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/amandioanastacio.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d3PERA DOS 3 VINT\u00c9NS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/amandioanastacio.de\/#website\",\"url\":\"http:\/\/amandioanastacio.de\/\",\"name\":\"Am\u00e2ndio Anast\u00e1cio\",\"description\":\"Theatre Author and Scenographer\",\"publisher\":{\"@id\":\"http:\/\/amandioanastacio.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/amandioanastacio.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/amandioanastacio.de\/#organization\",\"name\":\"Am\u00e2ndio Anast\u00e1cio\",\"url\":\"http:\/\/amandioanastacio.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\/\/amandioanastacio.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2018\/11\/amandio-logo.png\",\"contentUrl\":\"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2018\/11\/amandio-logo.png\",\"width\":350,\"height\":70,\"caption\":\"Am\u00e2ndio Anast\u00e1cio\"},\"image\":{\"@id\":\"http:\/\/amandioanastacio.de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/amandioanastacio.de\/#\/schema\/person\/4fbfed1ca752c302a8bc5a034d59adb6\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\/\/amandioanastacio.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9ebb955aa3dba291046d3ba3357c6097fc60c6e1baaa5a1eca42a5b562c47b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9ebb955aa3dba291046d3ba3357c6097fc60c6e1baaa5a1eca42a5b562c47b2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/amandioanastacio.de\/de\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d3PERA DOS 3 VINT\u00c9NS - Am\u00e2ndio Anast\u00e1cio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/","og_locale":"de_DE","og_type":"article","og_title":"\u00d3PERA DOS 3 VINT\u00c9NS - Am\u00e2ndio Anast\u00e1cio","og_description":"\u00d3PERA DOS 3 VINT\u00c9NS Die Dreigroschenoper Bertolt Brecht und Kurt Weill PROMO ANZEIGEN BUCHEN SIE DIESE SHOW MEINE ROLLE KREATION K\u00dcNSTLERISCHE LEITUNG SZENOGRAPHIE \u00dcBER \u00d3PERA DOS 3 VINT\u00c9NS Wir haben uns der Herausforderung dieses St\u00fcckes im Rahmen eines Berufspraktikums der Sch\u00fcler der Jazz-Schule Of\u00edcio das Artes gestellt. So schlugen wir vor, Die Dreigroschenoper mit dramaturgischer [&hellip;]","og_url":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/","og_site_name":"Am\u00e2ndio Anast\u00e1cio","article_published_time":"2020-03-03T15:18:01+00:00","article_modified_time":"2020-07-01T15:50:34+00:00","og_image":[{"width":422,"height":280,"url":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#article","isPartOf":{"@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/"},"author":{"name":"admin","@id":"http:\/\/amandioanastacio.de\/#\/schema\/person\/4fbfed1ca752c302a8bc5a034d59adb6"},"headline":"\u00d3PERA DOS 3 VINT\u00c9NS","datePublished":"2020-03-03T15:18:01+00:00","dateModified":"2020-07-01T15:50:34+00:00","mainEntityOfPage":{"@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"http:\/\/amandioanastacio.de\/#organization"},"image":{"@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage"},"thumbnailUrl":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/","url":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/","name":"\u00d3PERA DOS 3 VINT\u00c9NS - Am\u00e2ndio Anast\u00e1cio","isPartOf":{"@id":"http:\/\/amandioanastacio.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage"},"image":{"@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage"},"thumbnailUrl":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg","datePublished":"2020-03-03T15:18:01+00:00","dateModified":"2020-07-01T15:50:34+00:00","breadcrumb":{"@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#primaryimage","url":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg","contentUrl":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2019\/01\/opera2-1.jpg","width":422,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/amandioanastacio.de\/de\/opera-dos-3-vintens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/amandioanastacio.de\/de\/"},{"@type":"ListItem","position":2,"name":"\u00d3PERA DOS 3 VINT\u00c9NS"}]},{"@type":"WebSite","@id":"http:\/\/amandioanastacio.de\/#website","url":"http:\/\/amandioanastacio.de\/","name":"Am\u00e2ndio Anast\u00e1cio","description":"Theatre Author and Scenographer","publisher":{"@id":"http:\/\/amandioanastacio.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/amandioanastacio.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/amandioanastacio.de\/#organization","name":"Am\u00e2ndio Anast\u00e1cio","url":"http:\/\/amandioanastacio.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/amandioanastacio.de\/#\/schema\/logo\/image\/","url":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2018\/11\/amandio-logo.png","contentUrl":"https:\/\/amandioanastacio.de\/wp-content\/uploads\/2018\/11\/amandio-logo.png","width":350,"height":70,"caption":"Am\u00e2ndio Anast\u00e1cio"},"image":{"@id":"http:\/\/amandioanastacio.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/amandioanastacio.de\/#\/schema\/person\/4fbfed1ca752c302a8bc5a034d59adb6","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/amandioanastacio.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b9ebb955aa3dba291046d3ba3357c6097fc60c6e1baaa5a1eca42a5b562c47b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9ebb955aa3dba291046d3ba3357c6097fc60c6e1baaa5a1eca42a5b562c47b2?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/amandioanastacio.de\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/posts\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":3,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/posts\/1174\/revisions"}],"predecessor-version":[{"id":1179,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/posts\/1174\/revisions\/1179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/media\/1158"}],"wp:attachment":[{"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/categories?post=1174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amandioanastacio.de\/de\/wp-json\/wp\/v2\/tags?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}